{"id":43043,"date":"2025-07-06T10:29:07","date_gmt":"2025-07-06T13:29:07","guid":{"rendered":"https:\/\/somdepapo.com.br\/portal\/?p=43043"},"modified":"2025-07-06T10:29:07","modified_gmt":"2025-07-06T13:29:07","slug":"cuidado-com-quem-diz-que-te-ama-da-boca-pra-fora","status":"publish","type":"post","link":"https:\/\/somdepapo.com.br\/portal\/cuidado-com-quem-diz-que-te-ama-da-boca-pra-fora\/","title":{"rendered":"Cuidado com quem diz que te ama da boca pra fora"},"content":{"rendered":"<div id=\"m#msg-f:1836735215832567873\" class=\"mail-message expanded\">\n<div id=\"m#msg-f:1836735215832567873-header\" class=\"mail-message-header spacer\" style=\"text-align: right;\">Por Marize Reges&nbsp;<\/div>\n<div id=\"m#msg-f:1836735215832567873-content\" class=\"mail-message-content collapsible zoom-normal mail-show-images \" style=\"text-align: justify;\">\n<div class=\"clear\">\n<div>\n<div>\n<div dir=\"ltr\">\n<div>\n<div data-width=\"994.281px\" data-min-width=\"\" data-max-width=\"\">\n<div>\n<div>\n<div id=\"m_469281574856112340ydp1f0a1dd2yiv3055109309\" style=\"text-align: justify;\">\nQuantas vezes ouvimos \u201ceu te amo\u201d e nosso cora\u00e7\u00e3o quis acreditar, mesmo quando os gestos contavam outra hist\u00f3ria? Amar vai muito al\u00e9m de palavras soltas ao vento. Amar exige presen\u00e7a, respeito, const\u00e2ncia e, acima de tudo, verdade.<\/p>\n<p>Muitas mulheres, ao longo da vida, especialmente ap\u00f3s os 40, 50, 60 anos, j\u00e1 viveram rela\u00e7\u00f5es em que o \u201ceu te amo\u201d vinha carregado de inten\u00e7\u00f5es vazias. E isso deixa marcas. N\u00e3o \u00e9 sobre criar desconfian\u00e7a, mas sim aprender a observar o que h\u00e1 por tr\u00e1s das palavras.<\/p>\n<p>Amor que se sustenta s\u00f3 na fala, sem atitudes, \u00e9 amor pela metade \u2014 ou nem chega a ser amor. Quem ama, cuida. Quem ama, apoia, respeita o espa\u00e7o, celebra suas conquistas e caminha ao lado, n\u00e3o na frente nem atr\u00e1s.<\/p>\n<p>A maturidade nos convida a sermos mais seletivas, mais inteiras. J\u00e1 n\u00e3o precisamos nos contentar com migalhas emocionais. N\u00e3o aceitamos mais amores mornos, promessas sem a\u00e7\u00f5es, presen\u00e7as ausentes. Porque aprendemos que o maior amor que podemos cultivar \u00e9 o que temos por n\u00f3s mesmas.<\/p>\n<p>Ent\u00e3o, mulher, cuidado com quem diz que te ama da boca pra fora. Amor de verdade se sente na alma, n\u00e3o se escuta apenas no ouvido.&nbsp;<\/p><\/div>\n<\/div>\n<\/div>\n<div>&nbsp;<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"m#msg-f:1836735215832567873-footer\" class=\"mail-message-footer spacer collapsible\" style=\"text-align: justify;\">&nbsp;<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Marize Reges&nbsp; Quantas vezes ouvimos \u201ceu te amo\u201d e nosso cora\u00e7\u00e3o quis acreditar, mesmo quando os gestos contavam outra hist\u00f3ria? Amar vai muito al\u00e9m de palavras soltas ao vento. Amar exige presen\u00e7a, respeito, const\u00e2ncia e, acima de tudo, verdade. Muitas mulheres, ao longo da vida, especialmente ap\u00f3s os 40, 50, 60 anos, j\u00e1 viveram [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[2,275,31,41],"tags":[],"class_list":["post-43043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-mulher","category-noticias","category-ultimasnoticias"],"_links":{"self":[{"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/posts\/43043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/comments?post=43043"}],"version-history":[{"count":1,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/posts\/43043\/revisions"}],"predecessor-version":[{"id":43046,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/posts\/43043\/revisions\/43046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/media\/43045"}],"wp:attachment":[{"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/media?parent=43043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/categories?post=43043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/tags?post=43043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}