{"id":43604,"date":"2025-08-20T10:24:32","date_gmt":"2025-08-20T13:24:32","guid":{"rendered":"https:\/\/somdepapo.com.br\/portal\/?p=43604"},"modified":"2025-08-20T10:24:46","modified_gmt":"2025-08-20T13:24:46","slug":"menos-tendencia-mais-essencia","status":"publish","type":"post","link":"https:\/\/somdepapo.com.br\/portal\/menos-tendencia-mais-essencia\/","title":{"rendered":"Menos Tend\u00eancia, mais ess\u00eancia"},"content":{"rendered":"<p style=\"text-align: right;\">Por Karen Goldberg<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">As tend\u00eancias t\u00eam um charme perigoso: seduzem pela sensa\u00e7\u00e3o de estar em sintonia com a moda do momento, mas carregam uma data de validade invis\u00edvel.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Hoje elas parecem irresist\u00edveis, amanh\u00e3 soam ultrapassadas. Assim como aquela roupa com ombreiras enormes que j\u00e1 foi hit, mas hoje te d\u00e1 aquela sensa\u00e7\u00e3o de coisa ultrapassada.<\/p>\n<p style=\"text-align: justify;\">Eu sei disso porque vivi em uma casa assim. Quando eu era pequena, meus pais fizeram todo o projeto de interiores do apartamento com um arquiteto renomado. O resultado? A sala de estar foi capa do caderno de arquitetura de um importante jornal! \ud83c\udfe0\u2728<\/p>\n<p style=\"text-align: justify;\">Mas a casa ficou t\u00e3o datada que n\u00e3o resistiu ao tempo.&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u00c9 isso que a est\u00e9tica da moda faz: cria impacto imediato, mas deixa pouco espa\u00e7o para identidade e viv\u00eancia. Arquitetura n\u00e3o deveria ser sobre correr atr\u00e1s da est\u00e9tica do momento. Ela deve ser sobre traduzir hist\u00f3rias, desejos e modos de viver em espa\u00e7os que resistem ao tempo.&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u00c9 nisso que acredito: *menos tend\u00eancia, mais ess\u00eancia.*<\/p>\n<p style=\"text-align: justify;\">Ess\u00eancia \u00e9 o que permanece quando o excesso se desfaz. \u00c9 o detalhe que n\u00e3o envelhece porque nasce da verdade, n\u00e3o da moda do momento.<\/p>\n<p style=\"text-align: justify;\">Quando penso em projetos, busco criar espa\u00e7os que sustentem a vida real. Lugares que n\u00e3o precisam provar nada para ningu\u00e9m, porque carregam autenticidade.&nbsp;<\/p>\n<p style=\"text-align: justify;\">A verdadeira sofistica\u00e7\u00e3o n\u00e3o est\u00e1 em seguir a moda, mas em ter coragem de viver em um espa\u00e7o que \u00e9 s\u00f3 seu.&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u2728 *Tend\u00eancia \u00e9 ru\u00eddo. Ess\u00eancia \u00e9 sil\u00eancio.*&nbsp;<\/p>\n<p style=\"text-align: justify;\">E no sil\u00eancio, sua casa finalmente pode falar quem voc\u00ea \u00e9.<\/p>\n<p style=\"text-align: justify;\">S\u00f3 assim ela vai te acolher e te trazer o conforto que voc\u00ea almeja. \u2764\ufe0f<\/p>\n<p style=\"text-align: justify;\">E voc\u00ea, concorda? Me conta como s\u00e3o as coisas por a\u00ed! \ud83d\udcac\ud83d\udc47&nbsp;<\/p>\n<p style=\"text-align: justify;\">At\u00e9 a pr\u00f3xima.<\/p>\n<p style=\"text-align: justify;\">Arq. Karen Goldberg<\/p>\n<p style=\"text-align: justify;\">@kaparquitetura&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Karen Goldberg \u00e9 arquiteta e urbanista formada pela PUC-Rio desde 2009. \u00c0 frente da Kapa Arquitetura, seu trabalho \u00e9 ajudar pessoas a viverem em espa\u00e7os com significado \u2014 unindo est\u00e9tica, identidade e prop\u00f3sito em cada projeto.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Karen Goldberg &nbsp; As tend\u00eancias t\u00eam um charme perigoso: seduzem pela sensa\u00e7\u00e3o de estar em sintonia com a moda do momento, mas carregam uma data de validade invis\u00edvel.&nbsp; Hoje elas parecem irresist\u00edveis, amanh\u00e3 soam ultrapassadas. Assim como aquela roupa com ombreiras enormes que j\u00e1 foi hit, mas hoje te d\u00e1 aquela sensa\u00e7\u00e3o de coisa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[360,2,41],"tags":[],"class_list":["post-43604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquitetura","category-destaques","category-ultimasnoticias"],"_links":{"self":[{"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/posts\/43604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/comments?post=43604"}],"version-history":[{"count":1,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/posts\/43604\/revisions"}],"predecessor-version":[{"id":43606,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/posts\/43604\/revisions\/43606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/media\/43605"}],"wp:attachment":[{"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/media?parent=43604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/categories?post=43604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/somdepapo.com.br\/portal\/wp-json\/wp\/v2\/tags?post=43604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}